{"id":6453,"date":"2017-04-10T16:11:18","date_gmt":"2017-04-10T16:11:18","guid":{"rendered":"http:\/\/www.risk21.com\/ca\/?p=6453"},"modified":"2017-04-10T16:35:50","modified_gmt":"2017-04-10T16:35:50","slug":"quines-feines-les-mes-perilloses-del-mon","status":"publish","type":"post","link":"https:\/\/www.risk21.com\/ca\/quines-feines-les-mes-perilloses-del-mon\/","title":{"rendered":"Les feines m\u00e9s perilloses del m\u00f3n"},"content":{"rendered":"<p>Segons l\u2019Organitzaci\u00f3 Internacional del Treball (OIT), \u201cProp de 1.300 milions de treballadors a tot el m\u00f3n treballen pel sector agr\u00edcola, el que representa la meitat de la for\u00e7a de treball mundial. En termes de defuncions, lesions i problemes de salut relacionats amb la feina, l\u2019agricultura \u00e9s un dels tres sectors m\u00e9s perillosos conjuntament amb el sector de la \u00a0construcci\u00f3 i de la mineria\u201d . Font: <a href=\"http:\/\/www.quo.es\" target=\"_blank\">Quo.es<\/a><\/p>\n<p><a href=\"http:\/\/www.quo.es\/ser-humano\/cuales-son-los-trabajos-mas-peligrosos-del-mundo\" target=\"_blank\">VEURE NOT\u00cdCIA<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Segons l\u2019Organitzaci\u00f3 Internacional del Treball (OIT), \u201cProp de 1.300 milions de treballadors a tot el m\u00f3n treballen pel sector agr\u00edcola, el que representa la meitat de la for\u00e7a de treball mundial. En termes de defuncions, lesions i problemes de salut relacionats amb la feina, l\u2019agricultura \u00e9s un dels tres sectors m\u00e9s perillosos conjuntament amb el<br \/><a href=\"https:\/\/www.risk21.com\/ca\/quines-feines-les-mes-perilloses-del-mon\/\" class=\"more\">Llegir m\u00e9s<\/a><\/p>\n","protected":false},"author":3,"featured_media":6450,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[91],"tags":[153,95,152,136],"class_list":["post-6453","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticies-ca","tag-agricultura","tag-informacio-ca","tag-quo-es","tag-salut"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les feines m\u00e9s perilloses del m\u00f3n - Risk XXI<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.risk21.com\/ca\/quines-feines-les-mes-perilloses-del-mon\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les feines m\u00e9s perilloses del m\u00f3n - Risk XXI\" \/>\n<meta property=\"og:description\" content=\"Segons l\u2019Organitzaci\u00f3 Internacional del Treball (OIT), \u201cProp de 1.300 milions de treballadors a tot el m\u00f3n treballen pel sector agr\u00edcola, el que representa la meitat de la for\u00e7a de treball mundial. En termes de defuncions, lesions i problemes de salut relacionats amb la feina, l\u2019agricultura \u00e9s un dels tres sectors m\u00e9s perillosos conjuntament amb elLlegir m\u00e9s\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.risk21.com\/ca\/quines-feines-les-mes-perilloses-del-mon\/\" \/>\n<meta property=\"og:site_name\" content=\"Risk XXI\" \/>\n<meta property=\"article:published_time\" content=\"2017-04-10T16:11:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-04-10T16:35:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.risk21.com\/wp-content\/uploads\/2017\/04\/Acuerdos-con-TPP-regiran-comercio-global-agricola.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"603\" \/>\n\t<meta property=\"og:image:height\" content=\"520\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Risk XXI - Comunicacion\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"Risk XXI - Comunicacion\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.risk21.com\\\/ca\\\/quines-feines-les-mes-perilloses-del-mon\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.risk21.com\\\/ca\\\/quines-feines-les-mes-perilloses-del-mon\\\/\"},\"author\":{\"name\":\"Risk XXI - Comunicacion\",\"@id\":\"https:\\\/\\\/www.risk21.com\\\/#\\\/schema\\\/person\\\/541ded27b075c85a124af6989fc72b1d\"},\"headline\":\"Les feines m\u00e9s perilloses del m\u00f3n\",\"datePublished\":\"2017-04-10T16:11:18+00:00\",\"dateModified\":\"2017-04-10T16:35:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.risk21.com\\\/ca\\\/quines-feines-les-mes-perilloses-del-mon\\\/\"},\"wordCount\":82,\"image\":{\"@id\":\"https:\\\/\\\/www.risk21.com\\\/ca\\\/quines-feines-les-mes-perilloses-del-mon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.risk21.com\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/Acuerdos-con-TPP-regiran-comercio-global-agricola.jpg\",\"keywords\":[\"Agricultura\",\"Informaci\u00f3\",\"Quo.es\",\"salut\"],\"articleSection\":[\"Not\u00edcies\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.risk21.com\\\/ca\\\/quines-feines-les-mes-perilloses-del-mon\\\/\",\"url\":\"https:\\\/\\\/www.risk21.com\\\/ca\\\/quines-feines-les-mes-perilloses-del-mon\\\/\",\"name\":\"Les feines m\u00e9s perilloses del m\u00f3n - Risk XXI\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.risk21.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.risk21.com\\\/ca\\\/quines-feines-les-mes-perilloses-del-mon\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.risk21.com\\\/ca\\\/quines-feines-les-mes-perilloses-del-mon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.risk21.com\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/Acuerdos-con-TPP-regiran-comercio-global-agricola.jpg\",\"datePublished\":\"2017-04-10T16:11:18+00:00\",\"dateModified\":\"2017-04-10T16:35:50+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.risk21.com\\\/#\\\/schema\\\/person\\\/541ded27b075c85a124af6989fc72b1d\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.risk21.com\\\/ca\\\/quines-feines-les-mes-perilloses-del-mon\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.risk21.com\\\/ca\\\/quines-feines-les-mes-perilloses-del-mon\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.risk21.com\\\/ca\\\/quines-feines-les-mes-perilloses-del-mon\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.risk21.com\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/Acuerdos-con-TPP-regiran-comercio-global-agricola.jpg\",\"contentUrl\":\"https:\\\/\\\/www.risk21.com\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/Acuerdos-con-TPP-regiran-comercio-global-agricola.jpg\",\"width\":603,\"height\":520},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.risk21.com\\\/ca\\\/quines-feines-les-mes-perilloses-del-mon\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.risk21.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les feines m\u00e9s perilloses del m\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.risk21.com\\\/#website\",\"url\":\"https:\\\/\\\/www.risk21.com\\\/\",\"name\":\"Risk XXI\",\"description\":\"Prl &amp; Services\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.risk21.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.risk21.com\\\/#\\\/schema\\\/person\\\/541ded27b075c85a124af6989fc72b1d\",\"name\":\"Risk XXI - Comunicacion\",\"url\":\"https:\\\/\\\/www.risk21.com\\\/ca\\\/author\\\/comunicacion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les feines m\u00e9s perilloses del m\u00f3n - Risk XXI","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.risk21.com\/ca\/quines-feines-les-mes-perilloses-del-mon\/","og_locale":"ca_ES","og_type":"article","og_title":"Les feines m\u00e9s perilloses del m\u00f3n - Risk XXI","og_description":"Segons l\u2019Organitzaci\u00f3 Internacional del Treball (OIT), \u201cProp de 1.300 milions de treballadors a tot el m\u00f3n treballen pel sector agr\u00edcola, el que representa la meitat de la for\u00e7a de treball mundial. En termes de defuncions, lesions i problemes de salut relacionats amb la feina, l\u2019agricultura \u00e9s un dels tres sectors m\u00e9s perillosos conjuntament amb elLlegir m\u00e9s","og_url":"https:\/\/www.risk21.com\/ca\/quines-feines-les-mes-perilloses-del-mon\/","og_site_name":"Risk XXI","article_published_time":"2017-04-10T16:11:18+00:00","article_modified_time":"2017-04-10T16:35:50+00:00","og_image":[{"width":603,"height":520,"url":"https:\/\/www.risk21.com\/wp-content\/uploads\/2017\/04\/Acuerdos-con-TPP-regiran-comercio-global-agricola.jpg","type":"image\/jpeg"}],"author":"Risk XXI - Comunicacion","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"Risk XXI - Comunicacion"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.risk21.com\/ca\/quines-feines-les-mes-perilloses-del-mon\/#article","isPartOf":{"@id":"https:\/\/www.risk21.com\/ca\/quines-feines-les-mes-perilloses-del-mon\/"},"author":{"name":"Risk XXI - Comunicacion","@id":"https:\/\/www.risk21.com\/#\/schema\/person\/541ded27b075c85a124af6989fc72b1d"},"headline":"Les feines m\u00e9s perilloses del m\u00f3n","datePublished":"2017-04-10T16:11:18+00:00","dateModified":"2017-04-10T16:35:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.risk21.com\/ca\/quines-feines-les-mes-perilloses-del-mon\/"},"wordCount":82,"image":{"@id":"https:\/\/www.risk21.com\/ca\/quines-feines-les-mes-perilloses-del-mon\/#primaryimage"},"thumbnailUrl":"https:\/\/www.risk21.com\/wp-content\/uploads\/2017\/04\/Acuerdos-con-TPP-regiran-comercio-global-agricola.jpg","keywords":["Agricultura","Informaci\u00f3","Quo.es","salut"],"articleSection":["Not\u00edcies"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/www.risk21.com\/ca\/quines-feines-les-mes-perilloses-del-mon\/","url":"https:\/\/www.risk21.com\/ca\/quines-feines-les-mes-perilloses-del-mon\/","name":"Les feines m\u00e9s perilloses del m\u00f3n - Risk XXI","isPartOf":{"@id":"https:\/\/www.risk21.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.risk21.com\/ca\/quines-feines-les-mes-perilloses-del-mon\/#primaryimage"},"image":{"@id":"https:\/\/www.risk21.com\/ca\/quines-feines-les-mes-perilloses-del-mon\/#primaryimage"},"thumbnailUrl":"https:\/\/www.risk21.com\/wp-content\/uploads\/2017\/04\/Acuerdos-con-TPP-regiran-comercio-global-agricola.jpg","datePublished":"2017-04-10T16:11:18+00:00","dateModified":"2017-04-10T16:35:50+00:00","author":{"@id":"https:\/\/www.risk21.com\/#\/schema\/person\/541ded27b075c85a124af6989fc72b1d"},"breadcrumb":{"@id":"https:\/\/www.risk21.com\/ca\/quines-feines-les-mes-perilloses-del-mon\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.risk21.com\/ca\/quines-feines-les-mes-perilloses-del-mon\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.risk21.com\/ca\/quines-feines-les-mes-perilloses-del-mon\/#primaryimage","url":"https:\/\/www.risk21.com\/wp-content\/uploads\/2017\/04\/Acuerdos-con-TPP-regiran-comercio-global-agricola.jpg","contentUrl":"https:\/\/www.risk21.com\/wp-content\/uploads\/2017\/04\/Acuerdos-con-TPP-regiran-comercio-global-agricola.jpg","width":603,"height":520},{"@type":"BreadcrumbList","@id":"https:\/\/www.risk21.com\/ca\/quines-feines-les-mes-perilloses-del-mon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.risk21.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Les feines m\u00e9s perilloses del m\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/www.risk21.com\/#website","url":"https:\/\/www.risk21.com\/","name":"Risk XXI","description":"Prl &amp; Services","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.risk21.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Person","@id":"https:\/\/www.risk21.com\/#\/schema\/person\/541ded27b075c85a124af6989fc72b1d","name":"Risk XXI - Comunicacion","url":"https:\/\/www.risk21.com\/ca\/author\/comunicacion\/"}]}},"_links":{"self":[{"href":"https:\/\/www.risk21.com\/ca\/wp-json\/wp\/v2\/posts\/6453","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.risk21.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.risk21.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.risk21.com\/ca\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.risk21.com\/ca\/wp-json\/wp\/v2\/comments?post=6453"}],"version-history":[{"count":3,"href":"https:\/\/www.risk21.com\/ca\/wp-json\/wp\/v2\/posts\/6453\/revisions"}],"predecessor-version":[{"id":6458,"href":"https:\/\/www.risk21.com\/ca\/wp-json\/wp\/v2\/posts\/6453\/revisions\/6458"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.risk21.com\/ca\/wp-json\/wp\/v2\/media\/6450"}],"wp:attachment":[{"href":"https:\/\/www.risk21.com\/ca\/wp-json\/wp\/v2\/media?parent=6453"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.risk21.com\/ca\/wp-json\/wp\/v2\/categories?post=6453"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.risk21.com\/ca\/wp-json\/wp\/v2\/tags?post=6453"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}